{"id":8305,"date":"2020-05-26T11:23:01","date_gmt":"2020-05-26T11:23:01","guid":{"rendered":"https:\/\/davrontranslations.com\/faqs\/"},"modified":"2024-04-06T09:52:18","modified_gmt":"2024-04-06T07:52:18","slug":"faqs","status":"publish","type":"page","link":"https:\/\/davrontranslations.com\/fr\/faqs\/","title":{"rendered":"FAQs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8305\" class=\"elementor elementor-8305 elementor-715\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5af726e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5af726e\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6af8728\" data-id=\"6af8728\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a7a332 elementor-widget elementor-widget-heading\" data-id=\"5a7a332\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">FAQs<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b9a8f elementor-widget elementor-widget-heading\" data-id=\"f1b9a8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">D\u00e9marches Administratives<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d60524d elementor-widget elementor-widget-heading\" data-id=\"d60524d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vos questions les plus fr\u00e9quentes<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab4b4b5 elementor-widget elementor-widget-heading\" data-id=\"ab4b4b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Choisissez une destination pour vos documents :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6e810 elementor-widget elementor-widget-heading\" data-id=\"3e6e810\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-small\">Cliquez sur le drapeau du pays vis\u00e9<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-928427f elementor-widget elementor-widget-spacer\" data-id=\"928427f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17deb2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17deb2a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7ad4002\" data-id=\"7ad4002\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c77ed55 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c77ed55\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#uk%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2019\/06\/english-translation.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-10722\" alt=\"traduction en anglais\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e12b3eb\" data-id=\"e12b3eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d8a849 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6d8a849\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#france\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2019\/06\/francais-translation.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-10725\" alt=\"Traduction en fran\u00e7ais\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f060fcf\" data-id=\"f060fcf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c3f3c0 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9c3f3c0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#usa\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2019\/06\/usa-translation.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-10728\" alt=\"usa-traduction\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b91f74\" data-id=\"5b91f74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-453092a elementor-widget elementor-widget-image\" data-id=\"453092a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/elementor\/thumbs\/faqsnailv4-qg0r103bseziu21cty1tg4wnhqtf5qd2jzxmk7dlp0.png\" title=\"faqsnailv4\" alt=\"faqsnailv4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81b5cdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81b5cdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa458a8\" data-id=\"fa458a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-476196a elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"476196a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b0ec87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b0ec87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c064b04\" data-id=\"c064b04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25cdc0b elementor-widget elementor-widget-spacer\" data-id=\"25cdc0b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1de425 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1de425\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-641c4be\" data-id=\"641c4be\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d12398a elementor-widget elementor-widget-menu-anchor\" data-id=\"d12398a\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"uk\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68459ea elementor-widget elementor-widget-image\" data-id=\"68459ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2020\/06\/english-translation2.png\" class=\"attachment-thumbnail size-thumbnail wp-image-9470\" alt=\"Davron Translations Britsh\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8202b96 elementor-widget elementor-widget-heading\" data-id=\"8202b96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour l'administration britannique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef321c3 elementor-widget elementor-widget-toggle\" data-id=\"ef321c3\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2501\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2501\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Qu'est-ce qu'une traduction certifi\u00e9e ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2501\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2501\"><p><em>A) \u2605 Une traduction\u00a0<strong>certifi\u00e9e\u00a0<\/strong>comprend une d\u00e9claration expliquant qu&rsquo;il s&rsquo;agit d&rsquo;une \u00ab\u00a0traduction fid\u00e8le et exacte du document source\u00a0\u00bb, la date de la traduction, ainsi que le nom complet et les coordonn\u00e9es du repr\u00e9sentant de notre entreprise de traduction. Une traduction certifi\u00e9e est g\u00e9n\u00e9ralement demand\u00e9e par le registre civil ou pour les documents et actes juridiques, notari\u00e9s ou administratifs. Pour plus d&rsquo;informations sur les traductions certifi\u00e9es, veuillez consulter le site web <a href=\"https:\/\/www.gov.uk\/government\/organisations\/uk-visas-and-immigration\" rel=\"nofollow noopener\" target=\"_blank\">HOME OFFICE<\/a>. Pour les questions relatives \u00e0 une\u00a0<em>traduction asserment\u00e9e,\u00a0<\/em>consultez l&rsquo;onglet France sur notre page FAQ.<\/em><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2502\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2502\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Qu'est-ce qu'une apostille ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2502\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2502\"><p><em>A) \u2605<strong>L\u2019Apostille\u00a0<\/strong><em>est un certificat\u00a0<\/em>qui authentifie l&rsquo;origine d&rsquo;un acte public. Il facilite la circulation des actes publics dans les \u00c9tats signataires de la Convention de La Haye du 5 octobre 1961. L&rsquo;exigence d&rsquo;une apostille ou d&rsquo;une l\u00e9galisation d\u00e9pend du type de document et du pays de destination.<\/em><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2503\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2503\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q)Comment puis-je faire l\u00e9galiser mon document ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2503\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2503\"><p><strong>A) \u2605 Pour la\u00a0<\/strong><strong><strong>l\u00e9galisation<\/strong>, si vous \u00eates au Royaume-Uni, vous pouvez contacter le FCO \u00e0 l&rsquo;adresse suivante : Legalisation Office &#8211; Foreign and Commonwealth Office, Hanslope Park, Hanslope, Milton Keynes, MK19 7BH. Si vous \u00eates en France, veuillez consulter l&rsquo;onglet France sur notre page FAQ<\/strong><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2504\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2504\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Comment puis-je savoir si je dois obtenir une apostille ou l\u00e9galiser mon document ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2504\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2504\"><p><strong>A) \u2605 La n\u00e9cessit\u00e9 d&rsquo;une\u00a0apostille ou d&rsquo;une l\u00e9galisation\u00a0<\/strong>d\u00e9pend du type de document et du pays de destination. En g\u00e9n\u00e9ral, les documents qui doivent \u00eatre l\u00e9galis\u00e9s sont des actes priv\u00e9s et les documents qui ont besoin d&rsquo;une apostille sont les actes d&rsquo;\u00e9tat civil, les actes judiciaires, les d\u00e9clarations sous serment, les actes notari\u00e9s et les actes administratifs.<\/p><p>Davron Translations est recommand\u00e9 par le Consulat de France \u00e0 Londres (voir liste <a href=\"https:\/\/www.ambafrance-uk.org\/Les-traducteurs-enregistres-au-12105\" rel=\"nofollow noopener\" target=\"_blank\">: https:\/\/www.ambafrance-uk.org\/Les-traducteurs-enregistres-au-12105<\/a>)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c37ad7 elementor-widget elementor-widget-text-editor\" data-id=\"9c37ad7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Liens utiles pour l&rsquo;enregistrement dans ou \u00e0 partir du syst\u00e8me britannique :<\/h4><p><strong><u>Documents \u00e0 envoyer au Royaume-Uni<\/u><\/strong><\/p><p>Nous sommes membres de l&rsquo;ITI et nos traductions certifi\u00e9es peuvent \u00eatre utilis\u00e9es dans toutes les administrations britanniques (DVLA, Home Office, universit\u00e9s, etc.). Nous nous assurons que la certification comprend une d\u00e9claration d&rsquo;exactitude, sign\u00e9e et tamponn\u00e9e par la soci\u00e9t\u00e9 et son repr\u00e9sentant officiel.<\/p><p>Davron Translations est recommand\u00e9 par le Consulat de France \u00e0 Londres (voir liste : <a href=\"https:\/\/uk.ambafrance.org\/Les-traducteurs-et-les-interpretes-enregistres-au-consulat-general\" target=\"_blank\" rel=\"noopener\">https:\/\/uk.ambafrance.org\/Les-traducteurs-et-les-interpretes-enregistres-au-consulat-general<\/a>)<\/p><p>Si vous n&rsquo;\u00eates pas s\u00fbr de la fa\u00e7on d&rsquo;entamer votre proc\u00e9dure de visa ou votre inscription acad\u00e9mique et que vous avez besoin d&rsquo;aide pour proc\u00e9der \u00e0 ces d\u00e9marches, en personne, par courrier ou par t\u00e9l\u00e9phone, nous pouvons vous proposer un forfait pour vous accompagner.<\/p><p><strong>Sites web utiles<\/strong><\/p><p>Pour plus d&rsquo;informations sur la certification des documents et la certification des documents traduits, consultez le site <a href=\"https:\/\/www.gov.uk\/certifying-a-document\" rel=\"nofollow noopener\" target=\"_blank\">: https:\/\/www.gov.uk\/certifying-a-document<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2964ae4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2964ae4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-shrink\" href=\"https:\/\/quote.davrontranslations.com\/fr\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenez votre devis instantan\u00e9 gratuit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6c34c4 elementor-widget elementor-widget-spacer\" data-id=\"d6c34c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b1a6c9 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b1a6c9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a60e922 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a60e922\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62d7166\" data-id=\"62d7166\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e87912d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e87912d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8088717\" data-id=\"8088717\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aec13d8 elementor-widget elementor-widget-menu-anchor\" data-id=\"aec13d8\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"France\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f42cfb4 elementor-widget elementor-widget-image\" data-id=\"f42cfb4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2020\/06\/francais-translation2.png\" class=\"attachment-thumbnail size-thumbnail wp-image-9474\" alt=\"Davron Translations Fran\u00e7ais\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00690f5 elementor-widget elementor-widget-menu-anchor\" data-id=\"00690f5\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"france\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e99d093 elementor-widget elementor-widget-heading\" data-id=\"e99d093\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour l'administration fran\u00e7aise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96009b1 elementor-widget elementor-widget-toggle\" data-id=\"96009b1\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1571\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1571\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"><em>Q) Qu'est-ce qu'une traduction jur\u00e9e ou<em> traduction asserment\u00e9e ?<\/em><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1571\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1571\"><p><em>(A) \u2605 Une\u00a0traduction jur\u00e9e ou<strong>\u00a0<\/strong><em><strong>traduction asserment\u00e9e<\/strong>\u00a0<\/em>est assur\u00e9e par un traducteur expert judiciaire asserment\u00e9 aupr\u00e8s d&rsquo;une Cour d&rsquo;Appel, pouvant \u00e9galement \u00eatre inscrit sur la liste de la\u00a0<em>Cour de cassation<\/em>. La traduction asserment\u00e9e est consid\u00e9r\u00e9e comme un document officiel par les autorit\u00e9s fran\u00e7aises et \u00e9trang\u00e8res. Une traduction asserment\u00e9e est g\u00e9n\u00e9ralement demand\u00e9e pour les actes d&rsquo;\u00e9tat civil, les documents et actes juridiques, notari\u00e9s ou administratifs.<\/em><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1572\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1572\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Qu'est-ce qu'une apostille ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1572\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1572\"><p><strong>A) \u2605\u00a0<strong>L&rsquo;Apostille <\/strong><\/strong>est un\u00a0certificat qui authentifie l&rsquo;origine d&rsquo;un acte public. Il facilite la circulation des actes publics au sein des \u00c9tats signataires de la Convention de La Haye du 5 octobre 1961. Les documents qui peuvent n\u00e9cessiter une Apostille sont les actes d&rsquo;\u00e9tat civil, les documents juridiques, notari\u00e9s ou administratifs, les actes et les d\u00e9clarations sous serment. L&rsquo;apostille est d\u00e9livr\u00e9e en France par la Cour d&rsquo;Appel. Aux \u00c9tats-Unis, cette proc\u00e9dure est trait\u00e9e par le Bureau of Vital Records, le County Clerk&rsquo;s Office et le D\u00e9partement d&rsquo;\u00c9tat. Une fois l&rsquo;Apostille obtenue, le document peut \u00eatre directement transmis au pays de destination.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1573\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1573\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Comment un document est-il l\u00e9galis\u00e9 ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1573\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1573\"><p><strong>A) \u2605 La\u00a0l\u00e9galisation\u00a0d&rsquo;un document consiste en une signature authentifi\u00e9e et ne s&rsquo;applique qu&rsquo;aux actes priv\u00e9s.\u00a0Seul les documents fran\u00e7ais\u00a0peuvent \u00eatre l\u00e9galis\u00e9s en France<\/strong>. Les documents en langues \u00e9trang\u00e8res n\u00e9cessitent donc une traduction en fran\u00e7ais. Cette traduction doit \u00eatre fournie par un traducteur agr\u00e9\u00e9 dont la signature est inscrite au registre du commerce. La signature du traducteur peut \u00eatre l\u00e9galis\u00e9e \u00e0 la <a href=\"https:\/\/www.cci-paris-idf.fr\/\" rel=\"nofollow noopener\" target=\"_blank\">CCI (Chambre de commerce et d&rsquo;industrie) de Paris<\/a>\u00a0(2, rue de Viarmes &#8211; 75001 Paris &#8211; 0 820 012 112) et les documents peuvent \u00eatre apport\u00e9s \u00e0 votre mairie ou chez votre notaire pour compl\u00e9ter la l\u00e9galisation. Si vous \u00eates au Royaume-Uni, veuillez noter que Davron Translations est enregistr\u00e9 aupr\u00e8s du Consulat de France \u00e0 Londres (voir liste <a href=\"https:\/\/www.ambafrance-uk.org\/Les-traducteurs-enregistres-au-12105\" rel=\"nofollow noopener\" target=\"_blank\">: https:\/\/www.ambafrance-uk.org\/Les-traducteurs-enregistres-au-12105<\/a>)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1574\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1574\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Comment puis-je savoir si je dois obtenir une apostille ou l\u00e9galiser mon document ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1574\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1574\"><p><strong>A) \u2605 La n\u00e9cessit\u00e9 d&rsquo;une\u00a0apostille ou d&rsquo;une l\u00e9galisation\u00a0<\/strong>d\u00e9pend du type de document et du pays de destination. En g\u00e9n\u00e9ral, les documents qui doivent \u00eatre l\u00e9galis\u00e9s sont des actes priv\u00e9s et les documents qui n\u00e9cessitent une apostille sont les certificats d&rsquo;enregistrement de l&rsquo;\u00e9tat civil, les actes judiciaires, les d\u00e9clarations sous serment, les actes notari\u00e9s et les actes administratifs. Une liste d\u00e9taill\u00e9e des documents selon leur pays de destination peut \u00eatre consult\u00e9e \u00e0 cette adresse : <a href=\"https:\/\/www.diplomatie.gouv.fr\/fr\/services-aux-francais\/legalisation-et-notariat\/faire-legaliser-un-document\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.diplomatie.gouv.fr\/fr\/services-aux-francais\/legalisation-et-notariat\/faire-legaliser-un-document\/<\/a>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-937c46f elementor-widget elementor-widget-heading\" data-id=\"937c46f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Liens utiles pour toute inscription dans le syst\u00e8me fran\u00e7ais :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-631592f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"631592f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-41f5f05\" data-id=\"41f5f05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-530ca89 elementor-widget elementor-widget-text-editor\" data-id=\"530ca89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><strong>Pour une aide juridique, <\/strong>consultez cette\u00a0<a href=\"https:\/\/photos.state.gov\/libraries\/france\/325288\/service\/paris-attorneys.pdf\" target=\"_blank\" rel=\"nofollow noopener\">liste d&rsquo;avocats et de notaires<\/a>\u00a0fournie par l&rsquo;Ambassade des Etats-Unis, qui peut vous aider si vous cherchez un avocat am\u00e9ricain en France.<\/em><\/p><p>Voici \u00e9galement un lien tr\u00e8s utile vers la\u00a0<em><a href=\"https:\/\/paris.notaires.fr\/fr\" target=\"_blank\" rel=\"nofollow noopener\">Chambre des Notaires<\/a>\u00a0<\/em>qui r\u00e9pertorie de nombreux \u00ab\u00a0<strong>notaires<\/strong>\u00a0\u00bb (diff\u00e9rents des notaires publics am\u00e9ricains) dans Paris ou en proche banlieue.<\/p><p>Voici \u00e9galement un lien vers la\u00a0<em>Chambre Nationale<a href=\"https:\/\/www.huissier-justice.fr\/\" target=\"_blank\" rel=\"nofollow noopener\"> des Huissiers de Justice (juriste qui ex\u00e9cute<\/a>\u00a0et signifie les actes juridiques qui sont ex\u00e9cutoires en France)<\/em>.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bda6933\" data-id=\"bda6933\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d3ea6 elementor-widget elementor-widget-text-editor\" data-id=\"70d3ea6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pour les VISAS :<br \/>&#8211; <a href=\"https:\/\/www.prefecturedepolice.interieur.gouv.fr\/Demarches\/Particulier\/Ressortissants-etrangers\/Ressortissants-etrangers\" target=\"_blank\" rel=\"nofollow noopener\">Site web de la pr\u00e9fecture<br \/><\/a>&#8211; <a href=\"https:\/\/www.prefecturedepolice.interieur.gouv.fr\/Demarches\/Particulier\/Ressortissants-etrangers\/Ressortissants-etrangers\/La-naturalisation-ou-la-reintegration-dans-la-nationalite-francaise-procedure-par-decret\" target=\"_blank\" rel=\"nofollow noopener\">Site internet d&rsquo;information du gouvernement fran\u00e7ais<\/a><br \/>sur la naturalisation.<br \/>&#8211; <a href=\"https:\/\/www.diplomatie.gouv.fr\/fr\/venir-en-france\/demander-un-visa-pour-la-france\/\" target=\"_blank\" rel=\"nofollow noopener\">Demander un visa pour la France<\/a>.<\/strong><\/p><p>Vos documents doivent \u00eatre\u00a0<strong>l\u00e9galis\u00e9s ?<\/strong><\/p><p>Appelez ou prenez rendez-vous \u00e0 la CCI pr\u00e8s de la rue du Louvre pour votre demande pour la certification mat\u00e9rielle d&rsquo;une signature :<br \/><a href=\"https:\/\/www.entreprises.cci-paris-idf.fr\/web\/international\/legalisation-de-signature\" target=\"_blank\" rel=\"nofollow noopener\">C.C.I.P. \u00e0 la Bourse du Commerce<\/a>, au\u00a0<span style=\"font-size: 1rem;\">2 rue de Viarmes, 75001 Paris<\/span><\/p><p>Tel : 0820 012 112\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ff91ffa\" data-id=\"ff91ffa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9293521 elementor-widget elementor-widget-text-editor\" data-id=\"9293521\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/fr.usembassy.gov\/fr\/\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade des \u00c9tats-Unis<\/a><\/p><p><a href=\"https:\/\/www.gov.uk\/government\/world\/france.fr\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade britannique<\/a><\/p><p><a href=\"https:\/\/www.france.embassy.gov.au\/pari\/home.html\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade d&rsquo;Australie<\/a><\/p><p><a href=\"https:\/\/www.dfa.ie\/irish-embassy\/france\/\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade d&rsquo;Irlande<\/a><\/p><p><a href=\"https:\/\/www.canadainternational.gc.ca\/france\/index.aspx?lang=eng&amp;view=d\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade du Canada<\/a><\/p><p><a href=\"https:\/\/www.nzembassy.com\/france\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade de Nouvelle-Z\u00e9lande<\/a><\/p><p><a href=\"https:\/\/www.afriquesud.net\/\" target=\"_blank\" rel=\"nofollow noopener\">L&rsquo;ambassade d&rsquo;Afrique du Sud<\/a><\/p><p><a href=\"https:\/\/www.amb-chine.fr\/fra\/zgzfg\/zgsg\/lsb\/\" target=\"_blank\" rel=\"noopener\">Le Consulat de Chine<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-46840be elementor-align-center elementor-widget elementor-widget-button\" data-id=\"46840be\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-shrink\" href=\"https:\/\/quote.davrontranslations.com\/fr\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenez votre devis instantan\u00e9 gratuit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74f23f0 elementor-widget elementor-widget-text-editor\" data-id=\"74f23f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66d6416 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"66d6416\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9937cb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9937cb3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9014a7b\" data-id=\"9014a7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9e36dc elementor-widget elementor-widget-menu-anchor\" data-id=\"e9e36dc\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"usa\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc1467 elementor-widget elementor-widget-image\" data-id=\"4dc1467\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/2020\/06\/usa-translation2.png\" class=\"attachment-thumbnail size-thumbnail wp-image-9478\" alt=\"Davron Translations English\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5d834 elementor-widget elementor-widget-heading\" data-id=\"5c5d834\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pour l\u2019Administration am\u00e9ricaine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d66991 elementor-widget elementor-widget-toggle\" data-id=\"9d66991\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Qu'est-ce qu'une traduction certifi\u00e9e ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1651\"><p><em>(A) \u2605Une <strong>traduction certifi\u00e9e ou asserment\u00e9e<\/strong> <em>comprend un affidavit<\/em>\u00a0ou d\u00e9claration sous serment expliquant qu&rsquo;il s&rsquo;agit d&rsquo;une \u00ab\u00a0traduction fid\u00e8le et exacte du document source\u00a0\u00bb, la date de la traduction, ainsi que le nom complet et les coordonn\u00e9es du repr\u00e9sentant de notre entreprise de traduction. Une traduction certifi\u00e9e est g\u00e9n\u00e9ralement demand\u00e9e pour les documents et actes juridiques, notari\u00e9s ou administratifs. Davron Translations est enregistr\u00e9 aupr\u00e8s de l&rsquo;American Translators Association (ATA) sous le num\u00e9ro\u00a0<\/em><span style=\"font-family: Lato, sans-serif; font-size: 11pt;\">258831.\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1652\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1652\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Qu'est-ce qu'une apostille ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1652\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1652\"><p>A) \u2605 L&rsquo;<strong>Apostille<\/strong> est un certificat qui authentifie l&rsquo;origine d&rsquo;un acte public. Elle facilite la circulation des actes publics dans les \u00c9tats signataires de la Convention de La Haye du 5 octobre 1961. Les documents qui peuvent n\u00e9cessiter une Apostille sont les actes d&rsquo;\u00e9tat civil, les documents juridiques, notari\u00e9s ou administratifs, les actes et les d\u00e9clarations sous serment. L&rsquo;apostille est d\u00e9livr\u00e9e par la Cour d&rsquo;appel en France. Aux \u00c9tats-Unis, cette proc\u00e9dure est trait\u00e9e par le Bureau of Vital Records, le County Clerk&rsquo;s Office et le D\u00e9partement d&rsquo;\u00c9tat. Une fois l&rsquo;Apostille obtenue, le document peut \u00eatre directement transmis au pays de destination.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1653\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1653\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Comment un document est-il l\u00e9galis\u00e9 ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1653\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1653\"><p>A) \u2605 La <strong>l\u00e9galisation<\/strong> d&rsquo;un document consiste en une signature authentifi\u00e9e et ne s&rsquo;applique qu&rsquo;aux actes priv\u00e9s. Seuls les documents fran\u00e7ais peuvent \u00eatre l\u00e9galis\u00e9s en France. Par cons\u00e9quent, les documents en langues \u00e9trang\u00e8res n\u00e9cessitent une traduction en fran\u00e7ais. Cette traduction doit \u00eatre fournie par un traducteur agr\u00e9\u00e9 dont la signature est inscrite au registre du commerce. La signature du traducteur peut \u00eatre certifi\u00e9e mat\u00e9riellement \u00e0 la CCI (Chambre de commerce et d&rsquo;industrie) de Paris (2, rue de Viarmes &#8211; 75001 Paris &#8211; 0 820 012 112) et vous pourrez obtenir une <a href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F1412\" target=\"_blank\" rel=\"noopener\">copie conforme<\/a> de votre document en l&rsquo;apportant dans votre mairie ou chez votre notaire avant de proc\u00e9der \u00e0 sa l\u00e9galisation.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1654\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1654\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-angle-double-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Q) Comment puis-je savoir si je dois obtenir une apostille ou l\u00e9galiser mon document ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1654\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1654\"><p>A) \u2605 La n\u00e9cessit\u00e9 d&rsquo;une apostille ou d&rsquo;une l\u00e9galisation d\u00e9pend du type de document et du pays de destination. En g\u00e9n\u00e9ral, les documents qui doivent \u00eatre l\u00e9galis\u00e9s sont des actes priv\u00e9s et les documents qui n\u00e9cessitent une apostille sont les actes d&rsquo;\u00e9tat civil, les jugements, les d\u00e9clarations sous serment, les actes notari\u00e9s et les actes administratifs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22805bc elementor-widget elementor-widget-text-editor\" data-id=\"22805bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Liens utiles pour l&rsquo;enregistrement dans le syst\u00e8me am\u00e9ricain :<\/h4><p><strong><strong><u>Documents \u00e0 envoyer aux \u00c9tats-Unis<\/u><\/strong><\/strong><\/p><p>Pour des informations concernant les demandes de visa et expatriation aux Etats-Unis :<\/p><p><a href=\"https:\/\/fr.usembassy.gov\/fr\/visas-fr\/\" target=\"_blank\" rel=\"nofollow noopener\">Visa USA<\/a><\/p><p><a href=\"https:\/\/ais.usvisa-info.com\/fr-fr\/iv\/information\/lpr_help\" target=\"_blank\" rel=\"noopener\">Green cards\u00a0<\/a><\/p><p><a href=\"https:\/\/travel.state.gov\/content\/visas\/en\/immigrate\/immigrant-process.html\" rel=\"nofollow noopener\" target=\"_blank\">Immigration<\/a><\/p><p>Pour des informations g\u00e9n\u00e9rales sur votre expatriation,\u00a0ainsi que des informations concernant\u00a0<strong>une demande de visa : <a href=\"https:\/\/www.dhs.gov\/how-do-i\/move-united-states\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dhs.gov\/how-do-i\/move-united-states<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b087116 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b087116\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-shrink\" href=\"https:\/\/quote.davrontranslations.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenez un devis instantan\u00e9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bef6e elementor-widget elementor-widget-spacer\" data-id=\"f2bef6e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e09ae4 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9e09ae4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,21c3.3,0,8.3-0.9,15.7-7.1c6.6-5.4,4.4-9.3,2.4-10.3c-3.4-1.8-7.7,1.3-7.3,8.8C11.2,20,17.1,21,24,21&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69e76b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69e76b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a024b02\" data-id=\"a024b02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7c84cd elementor-widget elementor-widget-image\" data-id=\"f7c84cd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/davrontranslations.com\/wp-content\/uploads\/elementor\/thumbs\/faqsnailv4-qg0r103b6hlb11yhmhm8e3hgz2pltur7m3n1hi4zog.png\" title=\"faqsnailv4\" alt=\"faqsnailv4\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46fdfc57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46fdfc57\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f4517a5\" data-id=\"4f4517a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQs D\u00e9marches Administratives Vos questions les plus fr\u00e9quentes Choisissez une destination pour vos documents : Cliquez sur le drapeau du pays vis\u00e9 Pour l&rsquo;administration britannique Q) Qu&rsquo;est-ce qu&rsquo;une traduction certifi\u00e9e ? A) \u2605 Une traduction\u00a0certifi\u00e9e\u00a0comprend une d\u00e9claration expliquant qu&#8217;il s&#8217;agit d&#8217;une &#8220;traduction fid\u00e8le et exacte du document source&#8221;, la date de la traduction, ainsi que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8305","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"davrontranslations.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L\u2019image en vedette devrait \u00eatre au moins 200 par 200 pixels pour \u00eatre utilis\u00e9 par Facebook et d\u2019autres sites de m\u00e9dias sociaux.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"faqs","permalinkFormat":"https:\/\/davrontranslations.com\/fr\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/davrontranslations.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"Questions Fr\u00e9quentes - FAQs","description":"Consultez les r\u00e9ponses aux questions fr\u00e9quentes de nos clients et trouvez des liens utiles sur la traduction officielle asserment\u00e9e et la l\u00e9galisation","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"DavronTrad","primaryTerm":0,"authorName":"David Davron","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/davrontranslations.com\/fr\/","objectID":8305,"objectType":"post","locale":"fr","localeFull":"fr_FR","overlayImages":{"play":{"name":"Ic\u00f4ne de lecture","url":"https:\/\/davrontranslations.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/www\/davrontranslations_973\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Ic\u00f4ne GIF","url":"https:\/\/davrontranslations.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/www\/davrontranslations_973\/public\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/davrontranslations.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":true,"autoSuggestKeywords":true,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fdavrontranslations.com%2Ffr%2F&r=https%3A%2F%2Fdavrontranslations.com%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F8305%3Fnonce%3D4299dc0870&pro=1","maxTags":100,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/davrontranslations.com\/wp-content\/uploads\/2021\/05\/cropped-cropped-sigle_Davron-1-32x32.jpg","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":true,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Mettre \u00e0 niveau","trendsPreviewImage":"https:\/\/davrontranslations.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"searchIntents":[],"isAnalyticsConnected":false,"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/pages\/8305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/comments?post=8305"}],"version-history":[{"count":0,"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/pages\/8305\/revisions"}],"wp:attachment":[{"href":"https:\/\/davrontranslations.com\/fr\/wp-json\/wp\/v2\/media?parent=8305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}